{"id":23,"count":1,"description":"","link":"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/","name":"Senza categoria","slug":"senza-categoria","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Family in Tale - Libri personalizzati per bambini\" \/>\n<meta property=\"og:image\" content=\"https:\/\/familyintale.com\/it\/wp-content\/uploads\/2023\/04\/logo-family-in-tale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/categoria-libro\\\/senza-categoria\\\/\",\"url\":\"https:\\\/\\\/familyintale.com\\\/it\\\/categoria-libro\\\/senza-categoria\\\/\",\"name\":\"Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#website\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/familyintale.com\\\/it\\\/\",\"name\":\"Family in Tale - Libri personalizzati per bambini\",\"description\":\"Crea il tuo libro personalizzato di fiabe\",\"publisher\":{\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#organization\"},\"alternateName\":\"Family in Tale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/familyintale.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#organization\",\"name\":\"Family in Tale - Libri personalizzati per bambini\",\"url\":\"https:\\\/\\\/familyintale.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/familyintale.com\\\/it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-quadrato-family-in-tale.jpg\",\"contentUrl\":\"https:\\\/\\\/familyintale.com\\\/it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-quadrato-family-in-tale.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Family in Tale - Libri personalizzati per bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/familyintale.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100067299153661\",\"https:\\\/\\\/www.instagram.com\\\/personalized.fairy.tale\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/","og_locale":"it_IT","og_type":"article","og_title":"Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini","og_url":"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/","og_site_name":"Family in Tale - Libri personalizzati per bambini","og_image":[{"width":1280,"height":292,"url":"https:\/\/familyintale.com\/it\/wp-content\/uploads\/2023\/04\/logo-family-in-tale.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/","url":"https:\/\/familyintale.com\/it\/categoria-libro\/senza-categoria\/","name":"Senza categoria Archivi - Family in Tale - Libri personalizzati per bambini","isPartOf":{"@id":"https:\/\/familyintale.com\/it\/#website"},"inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/familyintale.com\/it\/#website","url":"https:\/\/familyintale.com\/it\/","name":"Family in Tale - Libri personalizzati per bambini","description":"Crea il tuo libro personalizzato di fiabe","publisher":{"@id":"https:\/\/familyintale.com\/it\/#organization"},"alternateName":"Family in Tale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/familyintale.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/familyintale.com\/it\/#organization","name":"Family in Tale - Libri personalizzati per bambini","url":"https:\/\/familyintale.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/familyintale.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/familyintale.com\/it\/wp-content\/uploads\/2023\/06\/logo-quadrato-family-in-tale.jpg","contentUrl":"https:\/\/familyintale.com\/it\/wp-content\/uploads\/2023\/06\/logo-quadrato-family-in-tale.jpg","width":1280,"height":1280,"caption":"Family in Tale - Libri personalizzati per bambini"},"image":{"@id":"https:\/\/familyintale.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100067299153661","https:\/\/www.instagram.com\/personalized.fairy.tale\/"]}]}},"_links":{"self":[{"href":"https:\/\/familyintale.com\/it\/wp-json\/wp\/v2\/product_cat\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/familyintale.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/familyintale.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/familyintale.com\/it\/wp-json\/wp\/v2\/product?product_cat=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}